{"id":4287,"date":"2025-01-28T16:19:15","date_gmt":"2025-01-28T16:19:15","guid":{"rendered":"https:\/\/parcostatella.com\/breakfast-room\/"},"modified":"2025-06-18T10:09:29","modified_gmt":"2025-06-18T10:09:29","slug":"breakfast-room","status":"publish","type":"page","link":"https:\/\/parcostatella.com\/en\/breakfast-room\/","title":{"rendered":"Breakfast room"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4287\" class=\"elementor elementor-4287 elementor-2701\">\n\t\t\t\t<div class=\"elementor-element elementor-element-923c371 e-flex e-con-boxed e-con e-parent\" data-id=\"923c371\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f385c06 elementor-widget elementor-widget-text-editor\" data-id=\"f385c06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Breakfast room<\/h1><p style=\"background: white; margin: 0cm 0cm 11.25pt 0cm;\"><span style=\"font-size: 11.0pt; font-family: 'Arial',sans-serif; color: #444444;\"><strong>Our guests will be lucky enough to have breakfast in a special room\u2026 an ancient stable!<\/strong><\/span><\/p><p style=\"background: white; margin: 0cm 0cm 11.25pt 0cm;\"><span style=\"font-size: 11.0pt; font-family: 'Arial',sans-serif; color: #444444;\">The two adjacent rooms, in ancient times, were indeed the stable and family carriage depot. The architecture of these rooms still preserves the original flooring and the manger with its wide arches, to avoid bruising the knees of the horses. Also particular attention has been paid to the lighting that recalls the town\u2019s old outdoor illuminations. The soft low voltage lighting warms up the metal of the tools that adorn the walls of the rooms. If you close your eyes you can feel the scent of freshly baked bread that melts in a hot cappuccino. . . .<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a49b1d4 e-flex e-con-boxed e-con e-parent\" data-id=\"a49b1d4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b2c5f15 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"b2c5f15\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-4287 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-2-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTItbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-2-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-3-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTMtbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-3-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-4-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTQtbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-4-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-5-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0NywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTUtbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-5-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-6-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0OCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTYtbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-6-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-7-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk0OSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTctbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-7-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-8-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTgtbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-8-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-9-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTktbWluLmpwZyIsInNsaWRlc2hvdyI6ImIyYzVmMTUifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-9-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-10-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTEwLW1pbi5qcGciLCJzbGlkZXNob3ciOiJiMmM1ZjE1In0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-10-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-11-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1MywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTExLW1pbi5qcGciLCJzbGlkZXNob3ciOiJiMmM1ZjE1In0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-11-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-12-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLTEyLW1pbi5qcGciLCJzbGlkZXNob3ciOiJiMmM1ZjE1In0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-12-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"b2c5f15\" data-elementor-lightbox-title=\"Sala Colazioni_-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzk1NSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMVwvU2FsYS1Db2xhemlvbmlfLW1pbi5qcGciLCJzbGlkZXNob3ciOiJiMmM1ZjE1In0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Sala-Colazioni_-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Breakfast room Our guests will be lucky enough to have breakfast in a special room\u2026 an ancient stable! The two adjacent rooms, in ancient times, were indeed the stable and family carriage depot. The architecture of these rooms still preserves the original flooring and the manger with its wide arches, to avoid bruising the knees &#8230;<\/p>\n","protected":false},"author":1,"featured_media":4165,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":90,"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-4287","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Breakfast room - Parcostatella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parcostatella.com\/en\/breakfast-room\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Breakfast room - Parcostatella\" \/>\n<meta property=\"og:description\" content=\"Breakfast room Our guests will be lucky enough to have breakfast in a special room\u2026 an ancient stable! The two adjacent rooms, in ancient times, were indeed the stable and family carriage depot. The architecture of these rooms still preserves the original flooring and the manger with its wide arches, to avoid bruising the knees ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parcostatella.com\/en\/breakfast-room\/\" \/>\n<meta property=\"og:site_name\" content=\"Parcostatella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T10:09:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/\",\"url\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/\",\"name\":\"Breakfast room - Parcostatella\",\"isPartOf\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg\",\"datePublished\":\"2025-01-28T16:19:15+00:00\",\"dateModified\":\"2025-06-18T10:09:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parcostatella.com\/en\/breakfast-room\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parcostatella.com\/en\/breakfast-room\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/parcostatella.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Breakfast room\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parcostatella.com\/en\/#website\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"name\":\"Parcostatella\",\"description\":\"Azienda turismo rurale\",\"publisher\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parcostatella.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\",\"name\":\"Parcostatella\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"width\":800,\"height\":238,\"caption\":\"Parcostatella\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\",\"https:\/\/www.instagram.com\/parcostatella\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Breakfast room - Parcostatella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parcostatella.com\/en\/breakfast-room\/","og_locale":"en_US","og_type":"article","og_title":"Breakfast room - Parcostatella","og_description":"Breakfast room Our guests will be lucky enough to have breakfast in a special room\u2026 an ancient stable! The two adjacent rooms, in ancient times, were indeed the stable and family carriage depot. The architecture of these rooms still preserves the original flooring and the manger with its wide arches, to avoid bruising the knees ...","og_url":"https:\/\/parcostatella.com\/en\/breakfast-room\/","og_site_name":"Parcostatella","article_publisher":"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","article_modified_time":"2025-06-18T10:09:29+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/","url":"https:\/\/parcostatella.com\/en\/breakfast-room\/","name":"Breakfast room - Parcostatella","isPartOf":{"@id":"https:\/\/parcostatella.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage"},"image":{"@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage"},"thumbnailUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg","datePublished":"2025-01-28T16:19:15+00:00","dateModified":"2025-06-18T10:09:29+00:00","breadcrumb":{"@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parcostatella.com\/en\/breakfast-room\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/#primaryimage","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/COlazione-min-1920x1280-2.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/parcostatella.com\/en\/breakfast-room\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parcostatella.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Breakfast room"}]},{"@type":"WebSite","@id":"https:\/\/parcostatella.com\/en\/#website","url":"https:\/\/parcostatella.com\/en\/","name":"Parcostatella","description":"Azienda turismo rurale","publisher":{"@id":"https:\/\/parcostatella.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parcostatella.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parcostatella.com\/en\/#organization","name":"Parcostatella","url":"https:\/\/parcostatella.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","width":800,"height":238,"caption":"Parcostatella"},"image":{"@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","https:\/\/www.instagram.com\/parcostatella\/"]}]}},"_links":{"self":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/comments?post=4287"}],"version-history":[{"count":3,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4287\/revisions"}],"predecessor-version":[{"id":4302,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4287\/revisions\/4302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/media\/4165"}],"wp:attachment":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/media?parent=4287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}