{"id":4273,"date":"2025-02-10T08:45:35","date_gmt":"2025-02-10T08:45:35","guid":{"rendered":"https:\/\/parcostatella.com\/mulberry-and-wisteria\/"},"modified":"2025-07-14T09:49:10","modified_gmt":"2025-07-14T09:49:10","slug":"mulberry-and-wisteria","status":"publish","type":"page","link":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/","title":{"rendered":"Mulberry and Wisteria"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4273\" class=\"elementor elementor-4273 elementor-2963\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23a7c72 e-flex e-con-boxed e-con e-parent\" data-id=\"23a7c72\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9dadbf0 elementor-widget elementor-widget-cs_title\" data-id=\"9dadbf0\" data-element_type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">DUS - TRIPLE - QUADRUPLE<\/span><\/div>\t            <h4 class=\"cs-title\">\n\t                Mulberry and Wisteria\t            <\/h4>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8e51d2 elementor-widget elementor-widget-spacer\" data-id=\"f8e51d2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d34c090 e-flex e-con-boxed e-con e-parent\" data-id=\"d34c090\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50427d4 elementor-align-left elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"50427d4\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-air-conditioner-3\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Air conditioning<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-wifi\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M634.91 154.88C457.74-8.99 182.19-8.93 5.09 154.88c-6.66 6.16-6.79 16.59-.35 22.98l34.24 33.97c6.14 6.1 16.02 6.23 22.4.38 145.92-133.68 371.3-133.71 517.25 0 6.38 5.85 16.26 5.71 22.4-.38l34.24-33.97c6.43-6.39 6.3-16.82-.36-22.98zM320 352c-35.35 0-64 28.65-64 64s28.65 64 64 64 64-28.65 64-64-28.65-64-64-64zm202.67-83.59c-115.26-101.93-290.21-101.82-405.34 0-6.9 6.1-7.12 16.69-.57 23.15l34.44 33.99c6 5.92 15.66 6.32 22.05.8 83.95-72.57 209.74-72.41 293.49 0 6.39 5.52 16.05 5.13 22.05-.8l34.44-33.99c6.56-6.46 6.33-17.06-.56-23.15z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wifi  <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">TV<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-refrigerator-1\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Refrigerator<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-hair-dryer\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Hair dryer  <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-coffee-cup\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Coffee<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-shampoo\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Shampoo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-towel-3\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Towels<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faa87ec elementor-widget elementor-widget-spacer\" data-id=\"faa87ec\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5807fa3 e-flex e-con-boxed e-con e-parent\" data-id=\"5807fa3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8492fbb elementor-widget elementor-widget-text-editor\" data-id=\"8492fbb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Originally dedicated to silkworm farming, the rooms can be arranged as two independent double bedrooms, each with private bathrooms, or combined into a cozy family suite for four. They are fully accessible to guests with reduced mobility. They are accessible to the disabled.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ff91b0d e-flex e-con-boxed e-con e-parent\" data-id=\"ff91b0d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5d4331 elementor-widget elementor-widget-spacer\" data-id=\"f5d4331\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23b004c e-flex e-con-boxed e-con e-parent\" data-id=\"23b004c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b1323fd e-flex e-con-boxed e-con e-parent\" data-id=\"b1323fd\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c05d53 gallery-spacing-custom elementor-widget elementor-widget-image-gallery\" data-id=\"0c05d53\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-4273 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-2-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA4OSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTItbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min.jpg'><img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-2-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-3-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5MCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTMtbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-3-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-4-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5MSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTQtbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min.jpg'><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-4-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-5-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5MiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTUtbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-5-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-6-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5MywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTYtbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-7-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5NCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTctbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-8-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5NSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTgtbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-8-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-9-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5NiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTktbWluLmpwZyIsInNsaWRlc2hvdyI6IjBjMDVkNTMifQ%3D%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-9-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-10-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5NywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTEwLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-10-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-11-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5OCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTExLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-11-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-12-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDA5OSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTEyLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-12-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-13-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwMCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTEzLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-13-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-14-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwMSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE0LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-14-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-15-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwMiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE1LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-15-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-16-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwMywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE2LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-16-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-17-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwNCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE3LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-17-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-18-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwNSwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE4LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-18-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-19-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwNiwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTE5LW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-19-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-20-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwNywidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLTIwLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-20-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"0c05d53\" data-elementor-lightbox-title=\"Gelso e Glicine-min\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDEwOCwidXJsIjoiaHR0cHM6XC9cL3BhcmNvc3RhdGVsbGEuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDI1XC8wMlwvR2Vsc28tZS1HbGljaW5lLW1pbi5qcGciLCJzbGlkZXNob3ciOiIwYzA1ZDUzIn0%3D\" href='https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DUS &#8211; TRIPLE &#8211; QUADRUPLE Mulberry and Wisteria Air conditioning Wifi TV Refrigerator Hair dryer Coffee Shampoo Towels Originally dedicated to silkworm farming, the rooms can be arranged as two independent double bedrooms, each with private bathrooms, or combined into a cozy family suite for four. They are fully accessible to guests with reduced mobility. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":4094,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":88,"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-4273","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mulberry and Wisteria - Parcostatella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mulberry and Wisteria - Parcostatella\" \/>\n<meta property=\"og:description\" content=\"DUS &#8211; TRIPLE &#8211; QUADRUPLE Mulberry and Wisteria Air conditioning Wifi TV Refrigerator Hair dryer Coffee Shampoo Towels Originally dedicated to silkworm farming, the rooms can be arranged as two independent double bedrooms, each with private bathrooms, or combined into a cozy family suite for four. They are fully accessible to guests with reduced mobility. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/\" \/>\n<meta property=\"og:site_name\" content=\"Parcostatella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T09:49:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/\",\"url\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/\",\"name\":\"Mulberry and Wisteria - Parcostatella\",\"isPartOf\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg\",\"datePublished\":\"2025-02-10T08:45:35+00:00\",\"dateModified\":\"2025-07-14T09:49:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/parcostatella.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mulberry and Wisteria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parcostatella.com\/en\/#website\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"name\":\"Parcostatella\",\"description\":\"Azienda turismo rurale\",\"publisher\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parcostatella.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\",\"name\":\"Parcostatella\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"width\":800,\"height\":238,\"caption\":\"Parcostatella\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\",\"https:\/\/www.instagram.com\/parcostatella\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mulberry and Wisteria - Parcostatella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/","og_locale":"en_US","og_type":"article","og_title":"Mulberry and Wisteria - Parcostatella","og_description":"DUS &#8211; TRIPLE &#8211; QUADRUPLE Mulberry and Wisteria Air conditioning Wifi TV Refrigerator Hair dryer Coffee Shampoo Towels Originally dedicated to silkworm farming, the rooms can be arranged as two independent double bedrooms, each with private bathrooms, or combined into a cozy family suite for four. They are fully accessible to guests with reduced mobility. ...","og_url":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/","og_site_name":"Parcostatella","article_publisher":"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","article_modified_time":"2025-07-14T09:49:10+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/","url":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/","name":"Mulberry and Wisteria - Parcostatella","isPartOf":{"@id":"https:\/\/parcostatella.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage"},"image":{"@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage"},"thumbnailUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg","datePublished":"2025-02-10T08:45:35+00:00","dateModified":"2025-07-14T09:49:10+00:00","breadcrumb":{"@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#primaryimage","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-7-min.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/parcostatella.com\/en\/mulberry-and-wisteria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parcostatella.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Mulberry and Wisteria"}]},{"@type":"WebSite","@id":"https:\/\/parcostatella.com\/en\/#website","url":"https:\/\/parcostatella.com\/en\/","name":"Parcostatella","description":"Azienda turismo rurale","publisher":{"@id":"https:\/\/parcostatella.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parcostatella.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parcostatella.com\/en\/#organization","name":"Parcostatella","url":"https:\/\/parcostatella.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","width":800,"height":238,"caption":"Parcostatella"},"image":{"@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","https:\/\/www.instagram.com\/parcostatella\/"]}]}},"_links":{"self":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/comments?post=4273"}],"version-history":[{"count":3,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4273\/revisions"}],"predecessor-version":[{"id":4364,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4273\/revisions\/4364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/media\/4094"}],"wp:attachment":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/media?parent=4273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}