{"id":4236,"date":"2023-03-11T06:04:53","date_gmt":"2023-03-11T06:04:53","guid":{"rendered":"https:\/\/parcostatella.com\/home\/"},"modified":"2025-07-14T09:33:38","modified_gmt":"2025-07-14T09:33:38","slug":"home","status":"publish","type":"page","link":"https:\/\/parcostatella.com\/en\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4236\" class=\"elementor elementor-4236 elementor-7\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b5c51a5 elementor-section-height-min-height cs-section-content-fullwidth cs_scroll_y_80 cs-parallax-on-scroll elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5b5c51a5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"80\" style=\"background-image: none;\" data-cs-background-image=\"http:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Home1.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4a41ebcf dark-color\" data-id=\"4a41ebcf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5255342d cs-animation-small-offset elementor-invisible elementor-widget elementor-widget-cs_title\" data-id=\"5255342d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <h1 class=\"cs-title\">\n\t                Rural Retreat\t            <\/h1>\t            <div class=\"cs-title-text\">\n\t                <p>A green island surrounded by the majesty of Mount Etna and the imposing walls of the Nebrodi Mountains.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b545afb cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1b545afb\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32d9da5a\" data-id=\"32d9da5a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a58b117 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a58b117\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2048 342\" width=\"1280\" height=\"1280\"><path transform=\"translate(188,2)\" d=\"m0 0h2l17 37 18 40 15 33h130l-2 4-11 13-9 11-14 17-11 13-11 14-13 15-9 11-5 6 1 14 17 105v5l-11-7-25-16-33-22-44-29-6 2-11 8-44 29-43 29-12 8-1-2 18-122-10-11-9-11-14-15-9-11-12-13-9-11-13-14-7-8-8-9v-1l40-1 78-1 12-1 13-25 12-22 14-27 12-22z\" fill=\"#B9A079\"><\/path><path transform=\"translate(1865,1)\" d=\"m0 0h2l17 37 16 35 16 36 1 2h131l-6 8-11 13-9 11-11 13-8 10-11 13-18 22-11 13-1 2 1 12 17 106v5l-12-7-43-29-16-10-42-28-5 2-54 36-43 29-12 8h-2l1-14 16-107-2-4-9-10-9-11-13-14-9-11-13-14-9-11-13-14-9-11-4-4v-2l128-2 5-8 14-27 12-22 14-27 12-22z\" fill=\"#B9A079\"><\/path><path transform=\"translate(1025,1)\" d=\"m0 0h2l17 37 16 36 15 32 2 5h131l-6 8-11 13-9 11-14 17-11 13-18 22-11 13-6 8 1 12 17 106v5l-12-7-39-26-44-29-18-12-5 2-43 29-44 29-22 15h-2l1-14 16-107-2-4-9-10-7-8-12-14-10-11-7-8-12-14-11-12-9-11-11-12v-2l130-2 2-6 14-27 12-22 15-29 12-22z\" fill=\"#B9A079\"><\/path><path transform=\"translate(1451,2)\" d=\"m0 0 3 3 18 39 16 36 15 32h130l-4 6-11 13-18 22-11 13-8 10-11 13-18 22-5 6 6 39 13 81-1 3-27-18-20-13-41-27-24-16-4 1-44 29-43 29-15 10-11 7 2-18 15-101v-6l-11-12-7-8-12-14-11-12-9-11-12-13-7-8-9-10-9-11-3-4 39-1 77-1 14-1 18-35 12-22 14-27 12-22z\" fill=\"#B9A079\"><\/path><path transform=\"translate(611,1)\" d=\"m0 0h2l18 39 15 33 16 35 1 3h131l-6 8-14 17-11 13-18 22-11 13-8 10-11 13-7 9 1 12 17 105v6l-12-7-39-26-41-27-21-14-5 2-43 29-44 29-22 15h-2l1-13 16-107-1-4-10-11-9-11-13-14-9-11-12-13-7-8-12-14-11-12-6-7v-2l129-2 16-31 12-22 14-27 12-22z\" fill=\"#B9A079\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b1495d2 elementor-widget elementor-widget-cs_title\" data-id=\"7b1495d2\" data-element_type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Welcome to our world<\/span><\/div>\t            <h2 class=\"cs-title\">\n\t                Parco Statella \u2013 Rural Retreat\t            <\/h2>\t            <div class=\"cs-title-text\">\n\t                <p> We are a sanctuary of fresh air, a well of quiet energy, a soft corner for stillness, a wide space for release.<br>We are the refuge where you come to escape the noise of the world, and the horizon from which you begin to explore the lands that make Sicily proud.<br>Rooted in our heritage, embraced by nature, and crafted to offer something truly different.<br>A stay of comfort and refined taste, surrounded by the colours of Mount Etna.<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-212c45e3 cs-section-content-fullwidth cs-animation-small-offset elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"212c45e3\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-76c691a9\" data-id=\"76c691a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cba2ecc elementor-widget elementor-widget-cs_gallery\" data-id=\"5cba2ecc\" data-element_type=\"widget\" data-widget_type=\"cs_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n            <div class=\"cs-gallery gap-16 gallery-carousel style-overflow\" data-column=\"3\" data-fade=\"\" data-autoplay=\"off\" data-autoplay-speed=\"5000\" data-show-arrows=\"on\" data-show-dots=\"\" data-variable-width=\"off\" data-overflow-style=\"on\" data-center-mode=\"\">\n                <div class=\"cs-gallery-wrap\">                    <div class=\"cs-gallery-item\"><img fetchpriority=\"high\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg\" class=\"attachment-full size-full wp-image-2404\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1.jpg\" class=\"attachment-full size-full wp-image-2402\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-2-600x400-1-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1.jpg\" class=\"attachment-full size-full wp-image-2401\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-3-600x400-1-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4.jpg\" class=\"attachment-full size-full wp-image-3333\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-4-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1.jpg\" class=\"attachment-full size-full wp-image-2403\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-1-600x400-1-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie.jpg\" class=\"attachment-full size-full wp-image-3324\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2.jpg\" class=\"attachment-full size-full wp-image-3325\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-2-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                    <div class=\"cs-gallery-item\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"600\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3.jpg\" class=\"attachment-full size-full wp-image-3326\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3.jpg 400w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Varie-3-100x150.jpg 100w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                    <\/div>                <\/div>\n            <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-603920c7 elementor-widget elementor-widget-text-editor\" data-id=\"603920c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Inspired by our history, surrounded by nature and designed to offer a different experience.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b6dacbf elementor-section-full_width elementor-section-height-min-height cs_scroll_y_80 cs-parallax-on-scroll elementor-section-height-default elementor-section-items-middle\" data-id=\"4b6dacbf\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"80\" style=\"background-image: none;\" data-cs-background-image=\"http:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Parcostatella-Fv2-min.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b6934e0 dark-color\" data-id=\"3b6934e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-268ef964 elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268ef964\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-35ceb183\" data-id=\"35ceb183\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fcb72bc elementor-widget elementor-widget-cs_title\" data-id=\"4fcb72bc\" data-element_type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center-mobile\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle\">Enjoy a first-class stay experience<\/span><\/div>\t            <h3 class=\"cs-title\">\n\t                The rooms\t            <\/h3>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-dd5c36d\" data-id=\"dd5c36d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f51a42f elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-cs_button\" data-id=\"6f51a42f\" data-element_type=\"widget\" data-widget_type=\"cs_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <a href=\"http:\/\/parcostatella.com\/gli-ambienti\/\" class=\"elementor-button-link button\" role=\"button\">\n            <span class=\"cs-btn-text\">SEE ALL ROOMS<\/span>        <\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-2ef1dbb e-grid e-con-boxed e-con e-parent\" data-id=\"2ef1dbb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1159896 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"1159896\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-3051\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Mansarda-6-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Attic room\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/mansarda\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2bab4b elementor-widget elementor-widget-cs_call_to_action\" data-id=\"d2bab4b\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2903\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/0D9A2485-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Lateral massar\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/massaro-laterale\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0283264 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"0283264\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2845\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-1536x1024.jpg 1536w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-2048x1366.jpg 2048w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-1920x1280.jpg 1920w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Massarotestata-min-150x100.jpg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Frontal mason\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/massaro-frontale\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-654f5fc elementor-widget elementor-widget-cs_call_to_action\" data-id=\"654f5fc\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-3100\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-cuori-7-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Ace of hearts\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/asso-di-cuori\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f951ce elementor-widget elementor-widget-cs_call_to_action\" data-id=\"4f951ce\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-3077\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Recaption-14-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Ace of diamonds\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"https:\/\/parcostatella.com\/en\/ace-of-diamonds\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ed0cfe elementor-widget elementor-widget-cs_call_to_action\" data-id=\"7ed0cfe\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2944\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Asso-di-fiori-7-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Ace of flowers\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/asso-di-fiori\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f42b4a3 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"f42b4a3\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2972\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Gelso-e-Glicine-6-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Mulberry and wisteria\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/gelso-e-glicine\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d6755e elementor-widget elementor-widget-cs_call_to_action\" data-id=\"6d6755e\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2667\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-1024x683.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/01\/Fruttiera-13-min.jpg 1500w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Fruit bowl\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/fruttiera\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dee599 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"1dee599\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t               \t<div class=\"cs-cta-img\">\n\t\t                    <img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-300x200.jpg\" class=\"attachment-medium size-medium wp-image-3454\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-300x200.jpg 300w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-1024x682.jpg 1024w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-768x512.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-1536x1024.jpg 1536w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-1920x1280.jpg 1920w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-1440x960.jpg 1440w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-1200x800.jpg 1200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-780x520.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-600x400.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-550x367.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-370x247.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-255x170.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min-150x100.jpg 150w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Casetta-esterno-min.jpg 2000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t                <\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h6 class=\"cs-cta-title cs-title color-white\">\n\t\t                Little house in the woods\t\t            <\/h6>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"https:\/\/parcostatella.com\/en\/house-in-the-woods\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-288d76d elementor-widget elementor-widget-cs_call_to_action\" data-id=\"288d76d\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-overlap content-middle with-inner-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t\t\t\t<div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">See details<\/span><\/div>\t\t            <h4 class=\"cs-cta-title cs-title color-white\">\n\t\t                Ace of diamonds\t\t            <\/h4>\t                <div class=\"cs-cta-btn\">\n\t                    <a class=\"button cs-btn-color-white cs-btn-underline\" role=\"button\" href=\"#\">\n\t                        <span class=\"cs-btn-text\">-<\/span>\t                    <\/a>\n\t                <\/div>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/parcostatella.com\/asso-di-cuori\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8233068 e-flex e-con-boxed e-con e-parent\" data-id=\"8233068\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d2bdd6 elementor-widget elementor-widget-spacer\" data-id=\"4d2bdd6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-69b9a5c cs_scroll_y_100 cs-section-content-fullwidth cs-parallax-on-scroll elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69b9a5c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"100\" style=\"background-image: none;\" data-cs-background-image=\"http:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Esterno1-min1920.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71e3dee dark-color\" data-id=\"71e3dee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546175f elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"546175f\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"flaticon flaticon-travel-map\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-763030e0 elementor-widget elementor-widget-cs_title\" data-id=\"763030e0\" data-element_type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <h2 class=\"cs-title\">\n\t                \u201cStays of comfort and taste among the shades of Etna.\u201d\t            <\/h2>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-855ef3d cs-section-content-fullwidth cs-animation-small-offset elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"855ef3d\" data-element_type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-27e92919\" data-id=\"27e92919\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-226b7ebe elementor-widget elementor-widget-cs_call_to_action\" data-id=\"226b7ebe\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-normal img-offset-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t                <div class=\"cs-cta-img-wrap\">\n\t\t\t\t\t        <div class=\"cs-cta-img\">\n\t\t\t\t\t            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-600x900.jpg\" class=\"attachment-cozystay_600x9999 size-cozystay_600x9999 wp-image-3518\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-600x900.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-683x1024.jpg 683w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-768x1152.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-780x1170.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-550x825.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min-100x150.jpg 100w, https:\/\/parcostatella.com\/wp-content\/uploads\/2025\/02\/Il-ristorante-12-min.jpg 1000w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t        <\/div>\n\t\t\t\t\t        <div class=\"cs-offset-border\"><\/div>\n\t\t\t\t\t\t<\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t            <h5 class=\"cs-cta-title cs-title\">\n\t\t                Restaurant\t\t            <\/h5>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"https:\/\/cozystay.loftocean.com\/island-resort\/spa-wellness\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2afe3239\" data-id=\"2afe3239\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2985f6f7 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"2985f6f7\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-normal img-offset-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t                <div class=\"cs-cta-img-wrap\">\n\t\t\t\t\t        <div class=\"cs-cta-img\">\n\t\t\t\t\t            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-600x900.jpg\" class=\"attachment-cozystay_600x9999 size-cozystay_600x9999 wp-image-2423\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-600x900.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-683x1024.jpg 683w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-768x1152.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-780x1170.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-550x825.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1-100x150.jpg 100w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Caffe01-min-1.jpg 800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t        <\/div>\n\t\t\t\t\t        <div class=\"cs-offset-border\"><\/div>\n\t\t\t\t\t\t<\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t            <h5 class=\"cs-cta-title cs-title\">\n\t\t                Services\t\t            <\/h5>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"https:\/\/cozystay.loftocean.com\/island-resort\/local-activities\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6cc00339\" data-id=\"6cc00339\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ed2d229 elementor-widget elementor-widget-cs_call_to_action\" data-id=\"7ed2d229\" data-element_type=\"widget\" data-widget_type=\"cs_call_to_action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"cs-cta cta-layout-text-normal img-offset-border text-center cta-hover-img-zoom\">\n            <div class=\"cs-cta-wrap\">\t\t                <div class=\"cs-cta-img-wrap\">\n\t\t\t\t\t        <div class=\"cs-cta-img\">\n\t\t\t\t\t            <img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"900\" src=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-600x900.jpg\" class=\"attachment-cozystay_600x9999 size-cozystay_600x9999 wp-image-2427\" alt=\"\" srcset=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-600x900.jpg 600w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-200x300.jpg 200w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-683x1024.jpg 683w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-768x1152.jpg 768w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-780x1170.jpg 780w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-550x825.jpg 550w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-370x555.jpg 370w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-255x383.jpg 255w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3-100x150.jpg 100w, https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Colazione01-min3.jpg 800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t        <\/div>\n\t\t\t\t\t        <div class=\"cs-offset-border\"><\/div>\n\t\t\t\t\t\t<\/div>                <div class=\"cs-cta-overlay\"><\/div>\n                <div class=\"cs-cta-content\">\t\t            <h5 class=\"cs-cta-title cs-title\">\n\t\t                Experiences\t\t            <\/h5>\t\t\t<\/div>                <a class=\"cs-cta-link\" href=\"http:\/\/www.parcostatella.com\/\"><\/a>            <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fcb733a cs_scroll_y_80 cs-section-content-fullwidth cs-parallax-on-scroll elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fcb733a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-cs-parallax-y=\"80\" style=\"background-image: none;\" data-cs-background-image=\"http:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Etna-3200-min-scaled.jpg\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-be31ebc dark-color\" data-id=\"be31ebc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c7c9085 elementor-widget elementor-widget-cs_title\" data-id=\"c7c9085\" data-element_type=\"widget\" data-widget_type=\"cs_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"cs-title-wrap text-center\">\t            <div class=\"cs-subtitle-wrap\"><span class=\"cs-subtitle color-white\">Our Guests\u2019 Voice<\/span><\/div>\t            <h6 class=\"cs-title\">\n\t                \"Everything here was fantastic: the staff, the layout of the rooms, the amenities, and the quality of the food. But the true highlight was the view from the mountains.\"\t            <\/h6>\t            <div class=\"cs-title-text\">\n\t                <p>Anna &#8211; TripAdvisor<\/p>\t            <\/div>        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-866cc40 cs-section-content-fullwidth elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"866cc40\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-87bf687\" data-id=\"87bf687\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rural Retreat A green island surrounded by the majesty of Mount Etna and the imposing walls of the Nebrodi Mountains. Welcome to our world Parco Statella \u2013 Rural Retreat We are a sanctuary of fresh air, a well of quiet energy, a soft corner for stillness, a wide space for release.We are the refuge where &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-wide-content.php","meta":{"iawp_total_views":1388,"cozystay_single_page_hide_site_header":"","cozystay_single_page_site_header_source":"","cozystay_single_page_custom_site_header":"0","cozystay_single_page_custom_sticky_site_header":"0","cozystay_single_page_hide_page_title":"","cozystay_single_page_header_section_size":"","cozystay_single_page_header_background_color":"","cozystay_single_page_header_background_position_x":"center","cozystay_single_page_header_background_position_y":"center","cozystay_single_page_header_background_size":"cover","cozystay_single_page_header_background_repeat":"off","cozystay_single_page_header_background_scroll":"on","cozystay_single_page_header_text_color":"","cozystay_single_page_header_show_breadcrumb":"","cozystay_single_page_site_footer_hide_main":"","cozystay_single_custom_site_footer_main_source":"","cozystay_single_custom_site_footer_main":"0","cozystay_single_page_site_footer_hide_above":"","cozystay_single_custom_site_footer_above_source":"","cozystay_single_custom_site_footer_above":"0","cozystay_single_page_site_footer_hide_instagram":"","cozystay_single_page_site_footer_hide_bottom":"","cozystay_single_custom_mobile_menu_source":"","cozystay_single_custom_mobile_menu":"0","cozystay_single_custom_mobile_menu_animation":"","cozystay_single_custom_mobile_menu_width":"","cozystay_single_custom_mobile_menu_custom_width":375,"footnotes":""},"class_list":["post-4236","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home - Parcostatella<\/title>\n<meta name=\"description\" content=\"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/parcostatella.com\/en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home - Parcostatella\" \/>\n<meta property=\"og:description\" content=\"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/parcostatella.com\/en\/\" \/>\n<meta property=\"og:site_name\" content=\"Parcostatella\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-14T09:33:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/parcostatella.com\/en\/\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"name\":\"Home - Parcostatella\",\"isPartOf\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg\",\"datePublished\":\"2023-03-11T06:04:53+00:00\",\"dateModified\":\"2025-07-14T09:33:38+00:00\",\"description\":\"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.\",\"breadcrumb\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/parcostatella.com\/en\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/#primaryimage\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/parcostatella.com\/en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/parcostatella.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/parcostatella.com\/en\/#website\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"name\":\"Parcostatella\",\"description\":\"Azienda turismo rurale\",\"publisher\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/parcostatella.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/parcostatella.com\/en\/#organization\",\"name\":\"Parcostatella\",\"url\":\"https:\/\/parcostatella.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"contentUrl\":\"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png\",\"width\":800,\"height\":238,\"caption\":\"Parcostatella\"},\"image\":{\"@id\":\"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT\",\"https:\/\/www.instagram.com\/parcostatella\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home - Parcostatella","description":"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/parcostatella.com\/en\/","og_locale":"en_US","og_type":"article","og_title":"Home - Parcostatella","og_description":"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.","og_url":"https:\/\/parcostatella.com\/en\/","og_site_name":"Parcostatella","article_publisher":"https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","article_modified_time":"2025-07-14T09:33:38+00:00","og_image":[{"width":400,"height":600,"url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/parcostatella.com\/en\/","url":"https:\/\/parcostatella.com\/en\/","name":"Home - Parcostatella","isPartOf":{"@id":"https:\/\/parcostatella.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/parcostatella.com\/en\/#primaryimage"},"image":{"@id":"https:\/\/parcostatella.com\/en\/#primaryimage"},"thumbnailUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg","datePublished":"2023-03-11T06:04:53+00:00","dateModified":"2025-07-14T09:33:38+00:00","description":"Parcostatella Rural Tourism Company - The Restaurant - the Relaxation and Conference Room - Billiard Room - Breakfast Room - The Permanent Show - The House in the Woods - The Park - The Territory - Randazzo - Etna. Sicily.","breadcrumb":{"@id":"https:\/\/parcostatella.com\/en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/parcostatella.com\/en\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/#primaryimage","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Homesli-0-600x400-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/parcostatella.com\/en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/parcostatella.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/parcostatella.com\/en\/#website","url":"https:\/\/parcostatella.com\/en\/","name":"Parcostatella","description":"Azienda turismo rurale","publisher":{"@id":"https:\/\/parcostatella.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/parcostatella.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/parcostatella.com\/en\/#organization","name":"Parcostatella","url":"https:\/\/parcostatella.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","contentUrl":"https:\/\/parcostatella.com\/wp-content\/uploads\/2024\/07\/Logo-Parco-statella-800.png","width":800,"height":238,"caption":"Parcostatella"},"image":{"@id":"https:\/\/parcostatella.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/p\/Parco-Statella-100063806072422\/?locale=it_IT","https:\/\/www.instagram.com\/parcostatella\/"]}]}},"_links":{"self":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/comments?post=4236"}],"version-history":[{"count":7,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4236\/revisions"}],"predecessor-version":[{"id":4350,"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/pages\/4236\/revisions\/4350"}],"wp:attachment":[{"href":"https:\/\/parcostatella.com\/en\/wp-json\/wp\/v2\/media?parent=4236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}